{"id":8102,"date":"2021-07-23T12:57:32","date_gmt":"2021-07-23T15:57:32","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=8102"},"modified":"2021-08-13T12:12:17","modified_gmt":"2021-08-13T15:12:17","slug":"momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/","title":{"rendered":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia"},"content":{"rendered":"\n<p class=\"texto-justificado\">A XIX SEMANA CIENT\u00cdFICA (SEC 2021) promovida Centro Universit\u00e1rio Santo Agostinho (UNIFSA) acontece entre 17 e 20 de agosto de 2021 e traz na programa\u00e7\u00e3o o Momento Educa\u00e7\u00e3o Conectada, visando dar destaque e esclarecimentos sobre o potencial de aprendizado e conhecimento viabilizado pelas aulas no meio digital.<\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background has-vivid-red-background-color\" href=\"https:\/\/www.sympla.com.br\/semana-cientifica-2021---o-valor-das-ciencias-para-sociedade-contemporanea-do-dia-a-dia-a-pandemia__1231255\"><strong>INSCREVA-SE NA SEC 2021<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background has-vivid-cyan-blue-background-color\" href=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/08\/Programa\u00e7\u00e3o-Completa-XIX-SEC-2021-1.pdf\">Confira a programa\u00e7\u00e3o completa!<\/a><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cVamos comentar e desmistificar como o aluno poder construir uma carreira profissional brilhante optando por estudar no Ensino a Dist\u00e2ncia (EAD) ou na semipresencialidade. Como conseguir ser um profissional de futuro\u201d, comentou.<\/p><cite>Profa. Ma. Eldelita &#8211; coordenadora do N\u00facleo de Ensino \u00e0 Dist\u00e2ncia \u2013 NEAD UNIFSA e membro da comiss\u00e3o organizadora da Sec 21.<\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2.jpg\" alt=\"\" class=\"wp-image-8104\" width=\"356\" height=\"357\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2.jpg 748w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2-298x300.jpg 298w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2-150x150.jpg 150w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2-230x230.jpg 230w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/1-FEED-2-110x110.jpg 110w\" sizes=\"(max-width: 356px) 100vw, 356px\" \/><\/figure><\/div>\n\n\n\n<p class=\"texto-justificado\">No primeiro dia de evento, das 18h30 \u00e0s 20h, acontece a webconfer\u00eancia \u201cSociedade da informa\u00e7\u00e3o e o papel do aluno como curador de conte\u00fado e informa\u00e7\u00e3o\u201d, ministrada pelos professores Ma. Daiana Garibaldi da Rocha, Sagah +Campus e o Me. Pedro Luiz Bulgarelli, +Campus.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cO primeiro momento a gente traz a percep\u00e7\u00e3o de como \u00e9 trabalhar a pesquisa em EAD. Ent\u00e3o a Daiana e o Pedro eles v\u00e3o trazer essa fala de como \u00e9 poss\u00edvel desenvolver pesquisa mesmo estando online\u201d.<\/p><cite> Profa. Ma. Eldelita &#8211; coordenadora do N\u00facleo de Ensino \u00e0 Dist\u00e2ncia \u2013 NEAD UNIFSA e membro da comiss\u00e3o organizadora da Sec 21. <\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2.jpg\" alt=\"\" class=\"wp-image-8105\" width=\"352\" height=\"354\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2.jpg 748w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2-298x300.jpg 298w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2-150x150.jpg 150w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2-230x230.jpg 230w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/2-FEED-2-110x110.jpg 110w\" sizes=\"(max-width: 352px) 100vw, 352px\" \/><\/figure><\/div>\n\n\n\n<p class=\"texto-justificado\">J\u00e1 no dia 19, tamb\u00e9m no hor\u00e1rio de 18h30 \u00e0s 20h, acontece a segunda webconfer\u00eancia do Momento Educa\u00e7\u00e3o Conectada, \u201cForma\u00e7\u00e3o continuada: voc\u00ea est\u00e1 preparado para estudar online?<strong>\u201d, <\/strong>conduzida pelas professoras Eldelita \u00c1guida Porf\u00edrio Franco, UNIFSA, e Profa. Dra. Izabel Herika Gomes Matias Cronemberger, coordenadora da P\u00d3S \/ UNIFSA. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cNeste segundo momento, n\u00f3s vamos debater exatamente como \u00e9 trabalhar a nossa carreira em EAD. Como \u00e9 poss\u00edvel perceber o curso, estar engajado, construir um curr\u00edculo rico optando pela modalidade do EAD ou semipresencial. Al\u00e9m disso, focar tamb\u00e9m na p\u00f3s-gradua\u00e7\u00e3o, j\u00e1 que existem os mestrados que trabalham com semipresencialidade e os doutorados sandu\u00edche\u201d, destaca.<\/p><cite>Profa. Ma. Eldelita &#8211; coordenadora do N\u00facleo de Ensino \u00e0 Dist\u00e2ncia \u2013 NEAD UNIFSA e membro da comiss\u00e3o organizadora da Sec 21.<\/cite><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background has-vivid-cyan-blue-background-color\">CONFIRA ABAIXO O V\u00cdDEO DA PROGRAMA\u00c7\u00c3O!<\/a><\/div>\n\n\n\n<figure class=\"wp-block-video\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A XIX SEMANA CIENT\u00cdFICA (SEC 2021) promovida Centro Universit\u00e1rio Santo Agostinho (UNIFSA) acontece entre 17 e 20 de agosto de 2021 e traz na programa\u00e7\u00e3o o Momento Educa\u00e7\u00e3o Conectada, visando dar destaque e esclarecimentos sobre o potencial de aprendizado e conhecimento viabilizado pelas aulas no meio digital. \u201cVamos comentar e desmistificar como o aluno poder<\/p>\n","protected":false},"author":9,"featured_media":8106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[538,517,539,492,494],"class_list":["post-8102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","tag-educacao-conectada","tag-momento","tag-sec-21","tag-semana-cientifica","tag-xix-semana-cientifica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"A XIX SEMANA CIENT\u00cdFICA (SEC 2021) promovida Centro Universit\u00e1rio Santo Agostinho (UNIFSA) acontece entre 17 e 20 de agosto de 2021 e traz na programa\u00e7\u00e3o o Momento Educa\u00e7\u00e3o Conectada, visando dar destaque e esclarecimentos sobre o potencial de aprendizado e conhecimento viabilizado pelas aulas no meio digital. \u201cVamos comentar e desmistificar como o aluno poder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-23T15:57:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T15:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La\u00eds Maria Matos Barradas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La\u00eds Maria Matos Barradas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/\"},\"author\":{\"name\":\"La\u00eds Maria Matos Barradas\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/person\\\/415c79d344f0e698644c1d29997b4ea8\"},\"headline\":\"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia\",\"datePublished\":\"2021-07-23T15:57:32+00:00\",\"dateModified\":\"2021-08-13T15:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/\"},\"wordCount\":371,\"publisher\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SITE-3.jpg\",\"keywords\":[\"educa\u00e7\u00e3o conectada\",\"momento\",\"sec 21\",\"semana cient\u00edfica\",\"XIX SEMANA CIENT\u00cdFICA\"],\"articleSection\":[\"Acontece na UNIFSA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/\",\"name\":\"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SITE-3.jpg\",\"datePublished\":\"2021-07-23T15:57:32+00:00\",\"dateModified\":\"2021-08-13T15:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SITE-3.jpg\",\"contentUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SITE-3.jpg\",\"width\":1010,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/unifsa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/unifsa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/person\\\/415c79d344f0e698644c1d29997b4ea8\",\"name\":\"La\u00eds Maria Matos Barradas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g\",\"caption\":\"La\u00eds Maria Matos Barradas\"},\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/author\\\/laismbarradas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/","og_locale":"pt_BR","og_type":"article","og_title":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"A XIX SEMANA CIENT\u00cdFICA (SEC 2021) promovida Centro Universit\u00e1rio Santo Agostinho (UNIFSA) acontece entre 17 e 20 de agosto de 2021 e traz na programa\u00e7\u00e3o o Momento Educa\u00e7\u00e3o Conectada, visando dar destaque e esclarecimentos sobre o potencial de aprendizado e conhecimento viabilizado pelas aulas no meio digital. \u201cVamos comentar e desmistificar como o aluno poder","og_url":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2021-07-23T15:57:32+00:00","article_modified_time":"2021-08-13T15:12:17+00:00","og_image":[{"width":1010,"height":431,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg","type":"image\/jpeg"}],"author":"La\u00eds Maria Matos Barradas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"La\u00eds Maria Matos Barradas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/"},"author":{"name":"La\u00eds Maria Matos Barradas","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8"},"headline":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia","datePublished":"2021-07-23T15:57:32+00:00","dateModified":"2021-08-13T15:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/"},"wordCount":371,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg","keywords":["educa\u00e7\u00e3o conectada","momento","sec 21","semana cient\u00edfica","XIX SEMANA CIENT\u00cdFICA"],"articleSection":["Acontece na UNIFSA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/","url":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/","name":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg","datePublished":"2021-07-23T15:57:32+00:00","dateModified":"2021-08-13T15:12:17+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2021\/07\/SITE-3.jpg","width":1010,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/momento-educacao-conectada-destaca-potencial-de-ensino-a-distancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Momento Educa\u00e7\u00e3o Conectada destaca potencial de Ensino a Dist\u00e2ncia"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8","name":"La\u00eds Maria Matos Barradas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g","caption":"La\u00eds Maria Matos Barradas"},"url":"https:\/\/unifsa.com.br\/site\/author\/laismbarradas\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/8102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=8102"}],"version-history":[{"count":8,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/8102\/revisions"}],"predecessor-version":[{"id":8362,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/8102\/revisions\/8362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/8106"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=8102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=8102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=8102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}