{"id":46580,"date":"2026-07-15T08:53:21","date_gmt":"2026-07-15T11:53:21","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=46580"},"modified":"2026-07-15T08:53:24","modified_gmt":"2026-07-15T11:53:24","slug":"prouni-2026-2-primeira-chamada","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/","title":{"rendered":"PROUNI 2026.2 | Primeira Chamada"},"content":{"rendered":"\n<p class=\"texto-justificado\">Informamos que o prazo para envio dos documentos para comprova\u00e7\u00e3o de informa\u00e7\u00f5es, pelos os estudantes classificados na 1\u00aa chamada do Programa Universidades Para Todos (PROUNI) 2026.2 ser\u00e1 do dia <strong>15 a 25 de julho<\/strong> com envio da documenta\u00e7\u00e3o para o email:<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center texto-justificado\">prouni@unifsa.com.br<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"texto-justificado\">Todos os documentos dever\u00e3o ser enviados em PDF, cada documento em um PDF diferente e todos os documentos em um \u00fanico e-mail;<\/li>\n\n\n\n<li class=\"texto-justificado\">Inserir no assunto: Primeira chamada PROUNI 2026.2, nome completo e curso;<\/li>\n\n\n\n<li class=\"texto-justificado\">Os documentos dever\u00e3o ser enviados pelo e\u2010mail do pr\u00f3prio aluno;<\/li>\n\n\n\n<li class=\"texto-justificado\">Em raz\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais (LGPD), todo contato com os alunos maiores de 18 anos ser\u00e1 feito exclusivamente com o pr\u00f3prio aluno, e em caso de menores, apenas com o respons\u00e1vel legal.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading texto-justificado has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-d3b8765f7c010c12e292028099347ee9\"><strong>Documenta\u00e7\u00e3o do aluno (Indispens\u00e1veis para a valida\u00e7\u00e3o):<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"texto-justificado\">Ficha de Inscri\u00e7\u00e3o (dispon\u00edvel no site do PROUNI, ap\u00f3s a complementa\u00e7\u00e3o da inscri\u00e7\u00e3o);<\/li>\n\n\n\n<li class=\"texto-justificado\">RG e CPF;<\/li>\n\n\n\n<li class=\"texto-justificado\">T\u00edtulo Eleitoral;<\/li>\n\n\n\n<li class=\"texto-justificado\">Reservista (para homens);<\/li>\n\n\n\n<li class=\"texto-justificado\">Certificado e Hist\u00f3rico do Ensino M\u00e9dio (ou Declara\u00e7\u00e3o de Conclus\u00e3o);<\/li>\n\n\n\n<li class=\"texto-justificado\">Carteira de Trabalho F\u00edsica ou Digital &#8211; caso n\u00e3o tenha renda declarada; F\u00cdSICA (Frente e verso da foto e pagina do ultimo contrato de trabalho assinado e a pagina seguinte;<\/li>\n\n\n\n<li class=\"texto-justificado\">Comprovante de Renda \u2013 Contracheque dos 3 \u00faltimos meses ou Declara\u00e7\u00e3o do Imposto de Renda (caso seja a pessoa que declarou a renda no grupo familiar);<\/li>\n\n\n\n<li class=\"texto-justificado\">Certid\u00e3o Nascimento ou Casamento (caso o aluno seja casado);<\/li>\n\n\n\n<li class=\"texto-justificado\">Comprovante de Resid\u00eancia (no nome do aluno ou de algu\u00e9m do grupo familiar).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading texto-justificado has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-a30b322ba8a1789c27ac19dd4bfa7bb3\"><strong>Do Grupo Familiar:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"texto-justificado\">RG e CPF;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"texto-justificado\">Carteira de Trabalho (f\u00edsica ou digital) de todos que forem maiores de 14 anos (exceto de quem declarou a renda);<\/li>\n\n\n\n<li class=\"texto-justificado\">Quem Declarou a Renda: apresentar o contracheque dos 3 \u00faltimos meses ou declara\u00e7\u00e3o do imposto de renda;<\/li>\n\n\n\n<li class=\"texto-justificado\">Se houver alguma crian\u00e7a no grupo familiar que n\u00e3o tenha CPF, anexar certid\u00e3o de nascimento;<\/li>\n\n\n\n<li>\u00c9 facultado ao coordenador do PROUNI na institui\u00e7\u00e3o pedir outros documentos eventualmente julgados necess\u00e1rios \u00e0 comprova\u00e7\u00e3o das informa\u00e7\u00f5es prestadas pelo candidato, referentes ao pr\u00f3prio candidato ou a membros do grupo familiar. (portaria Normativa n\u00ba 1, de 2 janeiro de 2015).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading texto-justificado has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-a28b136bbdf5085bdf9adce91c2796cf\"><strong>CONTATOS PROUNI UNIFSA<\/strong><\/h3>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-139da9580d2129c70f258af6b7adc4d7\">WhatsApp: (86) 3142-0785 <br>Fixo: (86) 3215-8710<\/p>\n\n\n\n<h3 class=\"wp-block-heading texto-justificado has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-54e44740d1bb57e8b4f95f3b9e4d446f\"><strong>HOR\u00c1RIO DE ATENDIMENTO:<\/strong><\/h3>\n\n\n\n<p>Segunda \u00e0 Sexta, das 8h \u00e0s 13h e de 14h \u00e0s 17h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informamos que o prazo para envio dos documentos para comprova\u00e7\u00e3o de informa\u00e7\u00f5es, pelos os estudantes classificados na 1\u00aa chamada do Programa Universidades Para Todos (PROUNI) 2026.2 ser\u00e1 do dia 15 a 25 de julho com envio da documenta\u00e7\u00e3o para o email: prouni@unifsa.com.br Documenta\u00e7\u00e3o do aluno (Indispens\u00e1veis para a valida\u00e7\u00e3o): Do Grupo Familiar: CONTATOS PROUNI UNIFSA<\/p>\n","protected":false},"author":11,"featured_media":46581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,529],"tags":[1831,207],"class_list":["post-46580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-prouni","tag-programa-universidade-para-todos","tag-prouni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"Informamos que o prazo para envio dos documentos para comprova\u00e7\u00e3o de informa\u00e7\u00f5es, pelos os estudantes classificados na 1\u00aa chamada do Programa Universidades Para Todos (PROUNI) 2026.2 ser\u00e1 do dia 15 a 25 de julho com envio da documenta\u00e7\u00e3o para o email: prouni@unifsa.com.br Documenta\u00e7\u00e3o do aluno (Indispens\u00e1veis para a valida\u00e7\u00e3o): Do Grupo Familiar: CONTATOS PROUNI UNIFSA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T11:53:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T11:53:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"PROUNI 2026.2 | Primeira Chamada\",\"datePublished\":\"2026-07-15T11:53:21+00:00\",\"dateModified\":\"2026-07-15T11:53:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/prouni-Site-2026.2-1920-x-805-px.webp\",\"keywords\":[\"Programa Universidade para Todos\",\"ProUni\"],\"articleSection\":[\"Acontece na UNIFSA\",\"PROUNI\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/\",\"name\":\"PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/prouni-Site-2026.2-1920-x-805-px.webp\",\"datePublished\":\"2026-07-15T11:53:21+00:00\",\"dateModified\":\"2026-07-15T11:53:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/prouni-Site-2026.2-1920-x-805-px.webp\",\"contentUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/prouni-Site-2026.2-1920-x-805-px.webp\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/prouni-2026-2-primeira-chamada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROUNI 2026.2 | Primeira Chamada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/unifsa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/unifsa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\\\/\\\/unifsa.com.br\\\/site\\\/author\\\/oceannyrakelly\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/","og_locale":"pt_BR","og_type":"article","og_title":"PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"Informamos que o prazo para envio dos documentos para comprova\u00e7\u00e3o de informa\u00e7\u00f5es, pelos os estudantes classificados na 1\u00aa chamada do Programa Universidades Para Todos (PROUNI) 2026.2 ser\u00e1 do dia 15 a 25 de julho com envio da documenta\u00e7\u00e3o para o email: prouni@unifsa.com.br Documenta\u00e7\u00e3o do aluno (Indispens\u00e1veis para a valida\u00e7\u00e3o): Do Grupo Familiar: CONTATOS PROUNI UNIFSA","og_url":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2026-07-15T11:53:21+00:00","article_modified_time":"2026-07-15T11:53:24+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp","type":"image\/webp"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"PROUNI 2026.2 | Primeira Chamada","datePublished":"2026-07-15T11:53:21+00:00","dateModified":"2026-07-15T11:53:24+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/"},"wordCount":390,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp","keywords":["Programa Universidade para Todos","ProUni"],"articleSection":["Acontece na UNIFSA","PROUNI"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/","url":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/","name":"PROUNI 2026.2 | Primeira Chamada - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp","datePublished":"2026-07-15T11:53:21+00:00","dateModified":"2026-07-15T11:53:24+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/07\/prouni-Site-2026.2-1920-x-805-px.webp","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/prouni-2026-2-primeira-chamada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"PROUNI 2026.2 | Primeira Chamada"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/46580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=46580"}],"version-history":[{"count":1,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/46580\/revisions"}],"predecessor-version":[{"id":46582,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/46580\/revisions\/46582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/46581"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=46580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=46580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=46580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}