{"id":44317,"date":"2026-04-01T18:08:37","date_gmt":"2026-04-01T21:08:37","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=44317"},"modified":"2026-04-01T18:08:48","modified_gmt":"2026-04-01T21:08:48","slug":"comunicado-recesso-semana-santa","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/","title":{"rendered":"Comunicado | Recesso Semana Santa"},"content":{"rendered":"\n<p>O Centro Universit\u00e1rio Santo Agostinho informa que estar\u00e1 em recesso em virtude da Semana Santa no per\u00edodo de <strong>2 a 5 de abril<\/strong>. As atividades acad\u00eamicas e administrativas ser\u00e3o retomadas normalmente na segunda-feira, <strong>6 de abril<\/strong>. Contamos com a compreens\u00e3o de todos e desejamos uma \u00f3tima Semana Santa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Universit\u00e1rio Santo Agostinho informa que estar\u00e1 em recesso em virtude da Semana Santa no per\u00edodo de 2 a 5 de abril. As atividades acad\u00eamicas e administrativas ser\u00e3o retomadas normalmente na segunda-feira, 6 de abril. Contamos com a compreens\u00e3o de todos e desejamos uma \u00f3tima Semana Santa.<\/p>\n","protected":false},"author":12,"featured_media":44319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,866],"tags":[271,1910],"class_list":["post-44317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-comunicado","tag-comunicado","tag-recesso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O Centro Universit\u00e1rio Santo Agostinho informa que estar\u00e1 em recesso em virtude da Semana Santa no per\u00edodo de 2 a 5 de abril. As atividades acad\u00eamicas e administrativas ser\u00e3o retomadas normalmente na segunda-feira, 6 de abril. Contamos com a compreens\u00e3o de todos e desejamos uma \u00f3tima Semana Santa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T21:08:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T21:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Estev\u00e3o Leite Cordeiro de Souza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estev\u00e3o Leite Cordeiro de Souza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\"},\"author\":{\"name\":\"Estev\u00e3o Leite Cordeiro de Souza\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf\"},\"headline\":\"Comunicado | Recesso Semana Santa\",\"datePublished\":\"2026-04-01T21:08:37+00:00\",\"dateModified\":\"2026-04-01T21:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\"},\"wordCount\":54,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp\",\"keywords\":[\"Comunicado\",\"Recesso\"],\"articleSection\":[\"Acontece na UNIFSA\",\"Comunicado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\",\"name\":\"Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp\",\"datePublished\":\"2026-04-01T21:08:37+00:00\",\"dateModified\":\"2026-04-01T21:08:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado | Recesso Semana Santa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf\",\"name\":\"Estev\u00e3o Leite Cordeiro de Souza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g\",\"caption\":\"Estev\u00e3o Leite Cordeiro de Souza\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/estevaocordeiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/","og_locale":"pt_BR","og_type":"article","og_title":"Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O Centro Universit\u00e1rio Santo Agostinho informa que estar\u00e1 em recesso em virtude da Semana Santa no per\u00edodo de 2 a 5 de abril. As atividades acad\u00eamicas e administrativas ser\u00e3o retomadas normalmente na segunda-feira, 6 de abril. Contamos com a compreens\u00e3o de todos e desejamos uma \u00f3tima Semana Santa.","og_url":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2026-04-01T21:08:37+00:00","article_modified_time":"2026-04-01T21:08:48+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp","type":"image\/webp"}],"author":"Estev\u00e3o Leite Cordeiro de Souza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Estev\u00e3o Leite Cordeiro de Souza","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/"},"author":{"name":"Estev\u00e3o Leite Cordeiro de Souza","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf"},"headline":"Comunicado | Recesso Semana Santa","datePublished":"2026-04-01T21:08:37+00:00","dateModified":"2026-04-01T21:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/"},"wordCount":54,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp","keywords":["Comunicado","Recesso"],"articleSection":["Acontece na UNIFSA","Comunicado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/","url":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/","name":"Comunicado | Recesso Semana Santa - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp","datePublished":"2026-04-01T21:08:37+00:00","dateModified":"2026-04-01T21:08:48+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2026\/04\/SITE-10-1.webp","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/comunicado-recesso-semana-santa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Comunicado | Recesso Semana Santa"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf","name":"Estev\u00e3o Leite Cordeiro de Souza","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g","caption":"Estev\u00e3o Leite Cordeiro de Souza"},"url":"https:\/\/unifsa.com.br\/site\/author\/estevaocordeiro\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/44317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=44317"}],"version-history":[{"count":2,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/44317\/revisions"}],"predecessor-version":[{"id":44321,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/44317\/revisions\/44321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/44319"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=44317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=44317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=44317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}