{"id":38397,"date":"2025-03-06T16:48:47","date_gmt":"2025-03-06T19:48:47","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=38397"},"modified":"2025-03-06T16:49:59","modified_gmt":"2025-03-06T19:49:59","slug":"selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/","title":{"rendered":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica"},"content":{"rendered":"\n<p class=\"texto-justificado\">O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Est\u00e9tica e Cosm\u00e9tica, <strong>seleciona alunos monitores para o IV Encontro de Est\u00e9tica e Cosm\u00e9tica.<\/strong> O prazo vai at\u00e9 o dia <strong>9 de mar\u00e7o<\/strong>, com o custo de 1kg de arroz ou feij\u00e3o (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). Os candidatos pr\u00e9-selecionados passar\u00e3o por uma entrevista, no dia 10 de mar\u00e7o, \u00e0s 15h30, na Sala 108 &#8211; anexo II, a fim de se analisar as habilidades atitudinais necess\u00e1rias \u00e0 proposta da extens\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/forms.gle\/8k6Kt5saoAARD4G57\">Inscreva-se para a monitoria<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/Edital-03-IV-Encontro-de-Estetica-e-Cosmetica-Selecao-de-Monitores.pdf\" style=\"background-color:#086499\">Edital de sele\u00e7\u00e3o completo<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-badc84741e47adf37119205e88090627\">Crit\u00e9rios para participar da sele\u00e7\u00e3o:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"texto-justificado\">Estar regularmente matriculado, cursando a partir do terceiro per\u00edodo do curso de Tecnologia<br>em Est\u00e9tica e Cosm\u00e9tica (presencial e semipresencial);<\/li>\n\n\n\n<li class=\"texto-justificado\">Ter disponibilidade nos hor\u00e1rios propostos;<\/li>\n\n\n\n<li class=\"texto-justificado\">Estar apto a iniciar as atividades relativas ao evento em 13\/03\/2025;<\/li>\n\n\n\n<li class=\"texto-justificado\">Ter entregue o quilo de arroz ou feij\u00e3o ap\u00f3s inscri\u00e7\u00e3o realizada.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Est\u00e9tica e Cosm\u00e9tica, seleciona alunos monitores para o IV Encontro de Est\u00e9tica e Cosm\u00e9tica. O prazo vai at\u00e9 o dia 9 de mar\u00e7o, com o custo de 1kg de arroz ou feij\u00e3o (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). Os candidatos pr\u00e9-selecionados passar\u00e3o por uma<\/p>\n","protected":false},"author":11,"featured_media":38429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,475],"tags":[1670,1184,1594,745],"class_list":["post-38397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-estetica-e-cosmetica","tag-encontro-de-estetica-e-cosmetica-do-unifsa","tag-estetica-e-cosmetica-semipresencial","tag-estetica-e-cosmetica-teresina","tag-selecao-de-monitores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Est\u00e9tica e Cosm\u00e9tica, seleciona alunos monitores para o IV Encontro de Est\u00e9tica e Cosm\u00e9tica. O prazo vai at\u00e9 o dia 9 de mar\u00e7o, com o custo de 1kg de arroz ou feij\u00e3o (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). Os candidatos pr\u00e9-selecionados passar\u00e3o por uma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T19:48:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T19:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica\",\"datePublished\":\"2025-03-06T19:48:47+00:00\",\"dateModified\":\"2025-03-06T19:49:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png\",\"keywords\":[\"Encontro de Est\u00e9tica e Cosm\u00e9tica do UNIFSA\",\"Est\u00e9tica e cosm\u00e9tica semipresencial\",\"Est\u00e9tica e Cosm\u00e9tica Teresina\",\"sele\u00e7\u00e3o de monitores\"],\"articleSection\":[\"Acontece na UNIFSA\",\"Est\u00e9tica e Cosm\u00e9tica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\",\"name\":\"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png\",\"datePublished\":\"2025-03-06T19:48:47+00:00\",\"dateModified\":\"2025-03-06T19:49:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png\",\"width\":1920,\"height\":855},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/","og_locale":"pt_BR","og_type":"article","og_title":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Est\u00e9tica e Cosm\u00e9tica, seleciona alunos monitores para o IV Encontro de Est\u00e9tica e Cosm\u00e9tica. O prazo vai at\u00e9 o dia 9 de mar\u00e7o, com o custo de 1kg de arroz ou feij\u00e3o (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). Os candidatos pr\u00e9-selecionados passar\u00e3o por uma","og_url":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2025-03-06T19:48:47+00:00","article_modified_time":"2025-03-06T19:49:59+00:00","og_image":[{"width":1920,"height":855,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png","type":"image\/png"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica","datePublished":"2025-03-06T19:48:47+00:00","dateModified":"2025-03-06T19:49:59+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/"},"wordCount":172,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png","keywords":["Encontro de Est\u00e9tica e Cosm\u00e9tica do UNIFSA","Est\u00e9tica e cosm\u00e9tica semipresencial","Est\u00e9tica e Cosm\u00e9tica Teresina","sele\u00e7\u00e3o de monitores"],"articleSection":["Acontece na UNIFSA","Est\u00e9tica e Cosm\u00e9tica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/","url":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/","name":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png","datePublished":"2025-03-06T19:48:47+00:00","dateModified":"2025-03-06T19:49:59+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2025\/03\/IV-Encontro-de-Estetica-e-Cosmetica-1920-x-855-px.png","width":1920,"height":855},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iv-encontro-de-estetica-e-cosmetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sele\u00e7\u00e3o de Monitores: IV Encontro de Est\u00e9tica e Cosm\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/38397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=38397"}],"version-history":[{"count":2,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/38397\/revisions"}],"predecessor-version":[{"id":38432,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/38397\/revisions\/38432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/38429"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=38397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=38397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=38397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}