{"id":35388,"date":"2024-09-16T16:27:58","date_gmt":"2024-09-16T19:27:58","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=35388"},"modified":"2024-09-16T16:28:00","modified_gmt":"2024-09-16T19:28:00","slug":"educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/","title":{"rendered":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso"},"content":{"rendered":"\n<p class=\"texto-justificado\">O curso de Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho promoveu, nesta quarta-feira (11), uma <strong>aula de atletismo especial para os alunos do primeiro e segundo per\u00edodos na Assessoria Love Run<\/strong>, localizada na Avenida Raul Lopes, Zona Leste de Teresina. A atividade fez parte da disciplina de Esportes de Marca, ministrada pela Profa. Dra. M\u00e1rcia Cristiane Ara\u00fajo, e teve como objetivo apresentar, na pr\u00e1tica, a presta\u00e7\u00e3o de servi\u00e7o de uma modalidade do atletismo, como a corrida.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote texto-justificado is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"texto-justificado\">Na sala de aula tudo \u00e9 lindo e maravilhoso, na pr\u00e1tica, \u00e9 um pouquinho diferente, existem outras habilidades que s\u00e3o exigidas dos nossos estudantes, que eles s\u00f3 desenvolvem no cotidiano. \u00c9 importante esta troca com a comunidade externa. Vendo a presta\u00e7\u00e3o de servi\u00e7o desde o atendimento ao cliente, at\u00e9 a finaliza\u00e7\u00e3o da sess\u00e3o de treinamento, o estudante na nossa gradua\u00e7\u00e3o consegue ter um contato real de como a prescri\u00e7\u00e3o de treinamento vai acontecer, onde ele deve interferir, e quais s\u00e3o as principais condutas que o mesmo precisar\u00e1 ter quando for ao mercado de trabalho, desta forma ele vai buscar concorrer nas vagas de est\u00e1gio com mais bagagem de conhecimento real.<\/p>\n<cite>Prof. Me. Alyson Felipe da Costa Sena, coordenador do curso de Educa\u00e7\u00e3o F\u00edsica<\/cite><\/blockquote>\n\n\n\n<p class=\"texto-justificado\">Segundo o coordenador, os alunos tiveram um acompanhamento desde o aquecimento da aula, com trabalhos de mobilidade articular; o aquecimento espec\u00edfico com a prepara\u00e7\u00e3o do corpo para a atividade principal, que foi uma corrida de pouco mais de tr\u00eas quil\u00f4metros. Ao t\u00e9rmino, houve uma pausa para hidrata\u00e7\u00e3o, que \u00e9 muito importante, principalmente no per\u00edodo do ano em que nos encontramos, e finalizou-se o treino com uma esp\u00e9cie de &#8220;volta \u00e0 calma&#8221;, em que o organismo \u00e9 preparado para encerrar a sess\u00e3o de treino, de tal forma que seu corpo relaxe ap\u00f3s o estresse promovido pela sess\u00e3o.<\/p>\n\n\n\n<p class=\"texto-justificado\">Na ocasi\u00e3o, a equipe de Relacionamento do UNIFSA tamb\u00e9m esteve presente, apoiando os alunos durante a aula e divulgando o vestibular da Institui\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"35398\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-35398\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1-1024x768.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1-300x225.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1-768x576.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1-1536x1152.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1025-1.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"35400\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1100-768x1024.jpeg\" alt=\"\" class=\"wp-image-35400\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1100-768x1024.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1100-225x300.jpeg 225w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1100-1152x1536.jpeg 1152w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1100.jpeg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"35399\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106-1024x768.jpeg\" alt=\"\" class=\"wp-image-35399\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106-1024x768.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106-300x225.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106-768x576.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106-1536x1152.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1106.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-b859cc5aa6c060ad269c259cf37e6900\">Confira alguns registros do momento:<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35401\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-1024x576.jpeg\" alt=\"\" class=\"wp-image-35401\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1037-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35403\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-1024x576.jpeg\" alt=\"\" class=\"wp-image-35403\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1044-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35407\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-1024x576.jpeg\" alt=\"\" class=\"wp-image-35407\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1048-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35404\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-1024x576.jpeg\" alt=\"\" class=\"wp-image-35404\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1058-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35405\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-35405\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1068-1-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35402\" src=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-1024x576.jpeg\" alt=\"\" class=\"wp-image-35402\" srcset=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-1024x576.jpeg 1024w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-300x169.jpeg 300w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-768x432.jpeg 768w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-1536x864.jpeg 1536w, https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1080-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O curso de Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho promoveu, nesta quarta-feira (11), uma aula de atletismo especial para os alunos do primeiro e segundo per\u00edodos na Assessoria Love Run, localizada na Avenida Raul Lopes, Zona Leste de Teresina. A atividade fez parte da disciplina de Esportes de Marca, ministrada pela Profa. Dra. M\u00e1rcia<\/p>\n","protected":false},"author":11,"featured_media":35406,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-35388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-educacao-fisica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O curso de Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho promoveu, nesta quarta-feira (11), uma aula de atletismo especial para os alunos do primeiro e segundo per\u00edodos na Assessoria Love Run, localizada na Avenida Raul Lopes, Zona Leste de Teresina. A atividade fez parte da disciplina de Esportes de Marca, ministrada pela Profa. Dra. M\u00e1rcia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T19:27:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T19:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2364\" \/>\n\t<meta property=\"og:image:height\" content=\"1330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso\",\"datePublished\":\"2024-09-16T19:27:58+00:00\",\"dateModified\":\"2024-09-16T19:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg\",\"articleSection\":[\"Acontece na UNIFSA\",\"Educa\u00e7\u00e3o F\u00edsica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\",\"name\":\"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg\",\"datePublished\":\"2024-09-16T19:27:58+00:00\",\"dateModified\":\"2024-09-16T19:28:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg\",\"width\":2364,\"height\":1330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/","og_locale":"pt_BR","og_type":"article","og_title":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O curso de Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho promoveu, nesta quarta-feira (11), uma aula de atletismo especial para os alunos do primeiro e segundo per\u00edodos na Assessoria Love Run, localizada na Avenida Raul Lopes, Zona Leste de Teresina. A atividade fez parte da disciplina de Esportes de Marca, ministrada pela Profa. Dra. M\u00e1rcia","og_url":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2024-09-16T19:27:58+00:00","article_modified_time":"2024-09-16T19:28:00+00:00","og_image":[{"width":2364,"height":1330,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg","type":"image\/jpeg"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso","datePublished":"2024-09-16T19:27:58+00:00","dateModified":"2024-09-16T19:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/"},"wordCount":368,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg","articleSection":["Acontece na UNIFSA","Educa\u00e7\u00e3o F\u00edsica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/","url":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/","name":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg","datePublished":"2024-09-16T19:27:58+00:00","dateModified":"2024-09-16T19:28:00+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/IMG_1008.jpeg","width":2364,"height":1330},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/educacao-fisica-promove-aula-externa-de-atletismo-para-alunos-do-1-e-2-periodo-do-curso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Educa\u00e7\u00e3o F\u00edsica promove aula externa de atletismo para alunos do 1\u00b0 e 2\u00b0 per\u00edodo do curso"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=35388"}],"version-history":[{"count":1,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35388\/revisions"}],"predecessor-version":[{"id":35408,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35388\/revisions\/35408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/35406"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=35388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=35388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=35388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}