{"id":35149,"date":"2024-09-05T15:55:29","date_gmt":"2024-09-05T18:55:29","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=35149"},"modified":"2024-09-05T15:55:32","modified_gmt":"2024-09-05T18:55:32","slug":"nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/","title":{"rendered":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se!"},"content":{"rendered":"\n<p class=\"texto-justificado\">O N\u00facleo de Rela\u00e7\u00f5es Internacionais &#8211; NRI, Centro Universit\u00e1rio Santo Agostinho realizar\u00e1 o <strong>bate-papo &#8220;Internacionaliza\u00e7\u00e3o: caminhos para forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos&#8221;<\/strong> no dia 24 de setembro, \u00e0s 15h, na Sala de Confer\u00eancia do pr\u00e9dio Anexo II. Para falar sobre a tem\u00e1tica, estar\u00e1 presente a <strong>Adviser Education USA e Gerente da Investe Piau\u00ed, Vanessa Nunes de Sousa Alencar Vasconcelos<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.sympla.com.br\/evento\/bate-papo-internacionalizacao-caminhos-para-formacao-e-qualificacao-nos-estados-unidos\/2629397\">Inscreva-se<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"texto-justificado\">Vanessa Vasconcelos possui doutorado em Administra\u00e7\u00e3o pela Universidade Nove de Julho (SP), mestrado em Administra\u00e7\u00e3o pela Universidade de Fortaleza &#8211; UNIFOR e p\u00f3s-gradua\u00e7\u00e3o em Planejamento em Turismo, Hotelaria e Eventos pela FAETE (PI) e em Educa\u00e7\u00e3o \u00e0 Dist\u00e2ncia pela NOVAFAPI (PI). Graduou-se em Administra\u00e7\u00e3o de Empresas com habilita\u00e7\u00e3o Turismo e Marketing pela Universidade de Nebraska nos Estados Unidos. Fez curso de empreendedorismo e inova\u00e7\u00e3o na Fran\u00e7a e participa do programa de acelera\u00e7\u00e3o empreendedora MIT REAP Cohort 2022-2024. Atualmente, \u00e9 professora adjunta do curso de Administra\u00e7\u00e3o e coordenadora do startup lab. Atuou como diretora do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica da Universidade Estadual do Piau\u00ed. Professora do Mestrado em Propriedade Intelectual e transfer\u00eancia deTecnologia para Inova\u00e7\u00e3o. Desenvolve pesquisas na \u00e1rea de gest\u00e3o organizacional, inova\u00e7\u00e3o e empreendedorismo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote texto-justificado is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"texto-justificado\">O bate papo ser\u00e1 importante para dar visibilidade ao programa &#8220;Conex\u00e3o com o Mundo&#8221; do UNIFSA e as oportunidades que ele proporciona para a comunidade acad\u00eamica. A presen\u00e7a da Dra. Vanessa ser\u00e1 uma excelente oportunidade para inspirar e engajar ainda mais nossos discentes e docentes em iniciativas de interc\u00e2mbio e colabora\u00e7\u00e3o com grandes centros de ensino e pesquisa ao redor do mundo, a\u00e7\u00f5es que est\u00e3o sendo trabalhadas pelo N\u00facleo de Rela\u00e7\u00f5es Internacionais.<\/p>\n<cite>Profa. Ma. Roberta Mara Ara\u00fajo, coordenadora de Extens\u00e3o e Monitoria do UNIFSA<\/cite><\/blockquote>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O N\u00facleo de Rela\u00e7\u00f5es Internacionais &#8211; NRI, Centro Universit\u00e1rio Santo Agostinho realizar\u00e1 o bate-papo &#8220;Internacionaliza\u00e7\u00e3o: caminhos para forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos&#8221; no dia 24 de setembro, \u00e0s 15h, na Sala de Confer\u00eancia do pr\u00e9dio Anexo II. Para falar sobre a tem\u00e1tica, estar\u00e1 presente a Adviser Education USA e Gerente da Investe Piau\u00ed, Vanessa<\/p>\n","protected":false},"author":11,"featured_media":35150,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,733],"tags":[],"class_list":["post-35149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-nucleo-de-relacoes-internacionais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O N\u00facleo de Rela\u00e7\u00f5es Internacionais &#8211; NRI, Centro Universit\u00e1rio Santo Agostinho realizar\u00e1 o bate-papo &#8220;Internacionaliza\u00e7\u00e3o: caminhos para forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos&#8221; no dia 24 de setembro, \u00e0s 15h, na Sala de Confer\u00eancia do pr\u00e9dio Anexo II. Para falar sobre a tem\u00e1tica, estar\u00e1 presente a Adviser Education USA e Gerente da Investe Piau\u00ed, Vanessa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T18:55:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T18:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se!\",\"datePublished\":\"2024-09-05T18:55:29+00:00\",\"dateModified\":\"2024-09-05T18:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg\",\"articleSection\":[\"Acontece na UNIFSA\",\"N\u00facleo de Rela\u00e7\u00f5es Internacionais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\",\"name\":\"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg\",\"datePublished\":\"2024-09-05T18:55:29+00:00\",\"dateModified\":\"2024-09-05T18:55:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/","og_locale":"pt_BR","og_type":"article","og_title":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O N\u00facleo de Rela\u00e7\u00f5es Internacionais &#8211; NRI, Centro Universit\u00e1rio Santo Agostinho realizar\u00e1 o bate-papo &#8220;Internacionaliza\u00e7\u00e3o: caminhos para forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos&#8221; no dia 24 de setembro, \u00e0s 15h, na Sala de Confer\u00eancia do pr\u00e9dio Anexo II. Para falar sobre a tem\u00e1tica, estar\u00e1 presente a Adviser Education USA e Gerente da Investe Piau\u00ed, Vanessa","og_url":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2024-09-05T18:55:29+00:00","article_modified_time":"2024-09-05T18:55:32+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg","type":"image\/jpeg"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se!","datePublished":"2024-09-05T18:55:29+00:00","dateModified":"2024-09-05T18:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/"},"wordCount":318,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg","articleSection":["Acontece na UNIFSA","N\u00facleo de Rela\u00e7\u00f5es Internacionais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/","url":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/","name":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se! - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg","datePublished":"2024-09-05T18:55:29+00:00","dateModified":"2024-09-05T18:55:32+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/09\/SITE-2024-09-05T135131.166.jpg","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/nri-promove-bate-papo-sobre-formacao-e-qualificacao-nos-estados-unidos-inscreva-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"NRI promove bate-papo sobre forma\u00e7\u00e3o e qualifica\u00e7\u00e3o nos Estados Unidos. Inscreva-se!"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=35149"}],"version-history":[{"count":2,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35149\/revisions"}],"predecessor-version":[{"id":35152,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/35149\/revisions\/35152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/35150"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=35149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=35149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=35149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}