{"id":31169,"date":"2024-05-10T19:49:31","date_gmt":"2024-05-10T22:49:31","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=31169"},"modified":"2024-05-13T13:40:38","modified_gmt":"2024-05-13T16:40:38","slug":"v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/","title":{"rendered":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio"},"content":{"rendered":"\n<p>O Centro Universit\u00e1rio Santo Agostinho, por meio das coordena\u00e7\u00f5es de Engenharias Civil, El\u00e9trica, de Produ\u00e7\u00e3o e de Software, anuncia a realiza\u00e7\u00e3o da V Semana da Engenharia do UNIFSA, de 16 a 18 de maio. O evento visa promover integra\u00e7\u00e3o multidisciplinar, atualiza\u00e7\u00e3o sobre as \u00faltimas tend\u00eancias do mercado e o desenvolvimento da lideran\u00e7a e a capacidade de trabalhar em equipes com a Gincana EngDay. Al\u00e9m disso, ter\u00e1 palestras, roda de conversa, visitas t\u00e9cnicas e minicursos, proporcionando oportunidades de networking e fomentando a inova\u00e7\u00e3o. O evento, que ter\u00e1 certifica\u00e7\u00e3o de 30h,\u00a0ser\u00e1 exclusivo para alunos e profissionais do UNIFSA, com inscri\u00e7\u00f5es abertas no dia 13 de maio, no valor de R$25.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.sympla.com.br\/evento\/v-semana-de-engenharia-do-unifsa\/2464195?_gl=1*14jlwan*_ga*MTI4NzkwMTg2Ny4xNjY5NDAyNzE3*_ga_KXH10SQTZF*MTcxNTM3ODAxNi41NS4xLjE3MTUzODEzMDMuNjAuMC4xNDcxOTgzMTAz\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Inscreva-se<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Com o objetivo de promover a integra\u00e7\u00e3o multidisciplinar e a atualiza\u00e7\u00e3o tecnol\u00f3gica, a V Semana da Engenharia do UNIFSA busca proporcionar uma experi\u00eancia enriquecedora e transformadora para todos os participantes. Ao reunir estudantes das engenharias do UNIFSA, o evento cria um ambiente prop\u00edcio para a troca de conhecimentos, experimenta\u00e7\u00f5es e perspectivas, fortalecendo assim os la\u00e7os entre as diversas \u00e1reas do conhecimento.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;A V Semana da Engenharia do UNIFSA, em sua quinta edi\u00e7\u00e3o, \u00e9 mais do que um evento; \u00e9 um s\u00edmbolo do sucesso cont\u00ednuo e do impacto positivo que essa atividade tem gerado ao longo dos anos. Ao promover o engajamento dos estudantes, a responsabilidade acad\u00eamica e o desenvolvimento de habilidades como lideran\u00e7a e trabalho em equipe, esta semana se consolida como uma atividade que traz resultados tang\u00edveis e duradouros. Al\u00e9m de agregar valor \u00e0 forma\u00e7\u00e3o dos participantes, impulsiona a inova\u00e7\u00e3o e fortalece conex\u00f5es dentro e fora da institui\u00e7\u00e3o.&#8221;<\/p>\n<cite><strong>Me. Ismeraldo Pereira de Oliveira, Coord. do evento e Coord. do curso de Engenharia Civil<\/strong>.<\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">CONFIRA A PROGRAMA\u00c7\u00c3O:<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>DATA<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>HOR\u00c1RIO<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>ATIVIDADE<\/strong><\/td><td><strong>MINISTRANTE<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">16\/5&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">17h \u00e0s 18h30<\/td><td class=\"has-text-align-left\" data-align=\"left\">Credenciamento<br>Loca: Sala de Reuni\u00e3o do Anexo II<\/td><td>Monitores<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Minicursos:<\/strong><\/td><td>&nbsp;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">16\/5&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&nbsp;18h30 \u00e0s 21h30<\/td><td class=\"has-text-align-left\" data-align=\"left\">MS Project<br>Local: Laborat\u00f3rio de Inform\u00e1tica VII<\/td><td>Danilo Teixeira Mascarenhas Andrade<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">16\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">18h30 \u00e0s 21h30<\/td><td class=\"has-text-align-left\" data-align=\"left\">Marketing e Empreendedorismo<br>Local: Sala de Inova\u00e7\u00e3o<\/td><td>Dr. Tonny Kerley de Alencar Rodrigues<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">16\/5&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&nbsp;18h30 \u00e0s 21h30<\/td><td class=\"has-text-align-left\" data-align=\"left\">Efici\u00eancia Energ\u00e9tica<br>Local: Sala 203<\/td><td>Ma. Jaciara Carvalho de Sousa Oliveira<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">16\/5&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">18h30 \u00e0s 21h30&nbsp;<\/td><td class=\"has-text-align-left\" data-align=\"left\">Metodologia \u00c1gil: Scrum <br>Local: Laborat\u00f3rio de Inform\u00e1tica V<\/td><td>Me. Danilo Faria Reis<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Visitas t\u00e9cnicas:<\/strong><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">17\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">8h \u00e0s 11h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Empresa de Manufatura<\/td><td>Jos\u00e9 Alberto Alencar Luz<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">8h \u00e0s 11h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Usina de Energia Solar<\/td><td>Edvan Carneiro Almeida<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">8h \u00e0s 11h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Obra de Constru\u00e7\u00e3o Civil<\/td><td>Ismeraldo P.de Oliveira<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">17\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">8h \u00e0s 11h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Data center virtual<br>Local: Sala de Inova\u00e7\u00e3o<\/td><td>Ma. Am\u00e9lia Ac\u00e1cia de M. Batista<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">17\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">18h30<\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Abertura Oficial<\/strong><br>Local: Audit\u00f3rio Cl\u00f3vis Melo \u2013 Anexo II<\/td><td><strong>Profa. Ma. Antonieta Lira e Silva<\/strong><br>Reitora e Pr\u00f3-Reitora de Ensino<br><br><strong>Ma. Indira Maria de Melo Lira Pereira da Silva<\/strong><br>Pr\u00f3-Reitora Administrativo e Financeiro<br><br><strong>Prof. Dr. Edj\u00f4fre Coelho de Oliveira<br><\/strong>Diretor de Ensino<br><br><strong>Profa. Dra. Ana Maria da Mata Almeida<\/strong><br>Assessora Pedag\u00f3gica<br><br><strong>Me. <strong>Ismeraldo Pereira de Oliveira<\/strong><\/strong><br>Coord. Engenharia Civil<br><br><strong>Me. Dra. Eldelita \u00c1guida Porf\u00edrio Franco<\/strong><br>Coord. Engenharia de Produ\u00e7\u00e3o<br><br><strong>Ma. Jaciara Carvalho de Sousa Oliveira<\/strong><br>Coord. Engenharia El\u00e9trica<br><br><strong>Prof.\u00aa Ma. Am\u00e9lia Ac\u00e1cia de Miranda Batista<\/strong><br>Coord. Engenharia de Software<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Palestra:<\/strong><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">17\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">19h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Compet\u00eancias comportamentais para gest\u00e3o nas engenharias.<br>Local: Audit\u00f3rio Cl\u00f3vis Melo \u2013 Anexo II<\/td><td><strong>Eng. Esp. Gerson Rios Ara\u00fajo<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Roda de Conversa:<\/strong><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">17\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">20h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Viv\u00eancias e experi\u00eancias no munda da<br>engenharia<br>Local: Audit\u00f3rio Cl\u00f3vis Melo \u2013 Anexo II<\/td><td><strong>Egressos das Engenharias<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>GINCANA ENGDAY:<\/strong><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">18\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">8h \u00e0s 11h<\/td><td class=\"has-text-align-left\" data-align=\"left\">Atividades de competi\u00e7\u00e3o entre equipes com 25 alunos.<br>Equipe interdisciplinar;<br>Perguntas e respostas;<br>Competi\u00e7\u00e3o: produto Inovador;<br>Arrecada\u00e7\u00e3o de produtos de higiene infantil;<br>Intera\u00e7\u00e3o com alunos do ensino m\u00e9dio;<br>Mostra de empresas (egressos)<br>Cada competi\u00e7\u00e3o ser\u00e1 graduada de 0 \u00e0 5 conforme julgamento da banca. Ser\u00e1 considerada vencedora a<br>equipe que obtiver em sua soma a maior pontua\u00e7\u00e3o.<\/td><td><strong>Me. <strong>Ismeraldo Pereira de Oliveira<\/strong><\/strong><br>Coord. Engenharia Civil<br><br><strong>Me. Dra. Eldelita \u00c1guida Porf\u00edrio Franco<\/strong><br>Coord. Engenharia de Produ\u00e7\u00e3o<br><br><strong>Ma. Jaciara Carvalho de Sousa Oliveira<\/strong><br>Coord. Engenharia El\u00e9trica<br><br><strong>Prof.\u00aa Ma. Am\u00e9lia Ac\u00e1cia de Miranda Batista<\/strong><br>Coord. Engenharia de Software<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-left\" data-align=\"left\"><\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">18\/5<\/td><td class=\"has-text-align-center\" data-align=\"center\">11h \u00e0s 13h<\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Momento Cultural<\/strong><\/td><td><strong>Banda Forr\u00f3 Choque<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Universit\u00e1rio Santo Agostinho, por meio das coordena\u00e7\u00f5es de Engenharias Civil, El\u00e9trica, de Produ\u00e7\u00e3o e de Software, anuncia a realiza\u00e7\u00e3o da V Semana da Engenharia do UNIFSA, de 16 a 18 de maio. O evento visa promover integra\u00e7\u00e3o multidisciplinar, atualiza\u00e7\u00e3o sobre as \u00faltimas tend\u00eancias do mercado e o desenvolvimento da lideran\u00e7a e a capacidade<\/p>\n","protected":false},"author":12,"featured_media":31235,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56,57,1531,58,1674],"tags":[125,112,1533,126,1752,581,1757,783,1756,1754,1755],"class_list":["post-31169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engenharia-civil","category-engenharia-producao","category-engenharia-de-software","category-engenharia-eletrica","category-eventos","tag-engenharia-civil","tag-engenharia-de-producao","tag-engenharia-de-software","tag-engenharia-eletrica","tag-engenharias","tag-eventos","tag-eventos-de-engenhria","tag-semana-de-engenharia","tag-semana-de-engenharia-do-unifsa","tag-v-semana-de-engenharia","tag-v-semana-de-engenharia-do-unifsa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O Centro Universit\u00e1rio Santo Agostinho, por meio das coordena\u00e7\u00f5es de Engenharias Civil, El\u00e9trica, de Produ\u00e7\u00e3o e de Software, anuncia a realiza\u00e7\u00e3o da V Semana da Engenharia do UNIFSA, de 16 a 18 de maio. O evento visa promover integra\u00e7\u00e3o multidisciplinar, atualiza\u00e7\u00e3o sobre as \u00faltimas tend\u00eancias do mercado e o desenvolvimento da lideran\u00e7a e a capacidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T22:49:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-13T16:40:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Estev\u00e3o Leite Cordeiro de Souza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estev\u00e3o Leite Cordeiro de Souza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\"},\"author\":{\"name\":\"Estev\u00e3o Leite Cordeiro de Souza\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf\"},\"headline\":\"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio\",\"datePublished\":\"2024-05-10T22:49:31+00:00\",\"dateModified\":\"2024-05-13T16:40:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\"},\"wordCount\":718,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png\",\"keywords\":[\"Engenharia Civil\",\"Engenharia de Produ\u00e7\u00e3o\",\"Engenharia de Software\",\"Engenharia El\u00e9trica\",\"engenharias\",\"EVENTOS\",\"Eventos de Engenhria\",\"Semana de Engenharia\",\"Semana de Engenharia do UNIFSA\",\"V Semana de Engenharia\",\"V Semana de Engenharia do UNIFSA\"],\"articleSection\":[\"Engenharia Civil\",\"Engenharia de Produ\u00e7\u00e3o\",\"Engenharia de Software\",\"Engenharia El\u00e9trica\",\"Eventos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\",\"name\":\"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png\",\"datePublished\":\"2024-05-10T22:49:31+00:00\",\"dateModified\":\"2024-05-13T16:40:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf\",\"name\":\"Estev\u00e3o Leite Cordeiro de Souza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g\",\"caption\":\"Estev\u00e3o Leite Cordeiro de Souza\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/estevaocordeiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/","og_locale":"pt_BR","og_type":"article","og_title":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O Centro Universit\u00e1rio Santo Agostinho, por meio das coordena\u00e7\u00f5es de Engenharias Civil, El\u00e9trica, de Produ\u00e7\u00e3o e de Software, anuncia a realiza\u00e7\u00e3o da V Semana da Engenharia do UNIFSA, de 16 a 18 de maio. O evento visa promover integra\u00e7\u00e3o multidisciplinar, atualiza\u00e7\u00e3o sobre as \u00faltimas tend\u00eancias do mercado e o desenvolvimento da lideran\u00e7a e a capacidade","og_url":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2024-05-10T22:49:31+00:00","article_modified_time":"2024-05-13T16:40:38+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png","type":"image\/png"}],"author":"Estev\u00e3o Leite Cordeiro de Souza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Estev\u00e3o Leite Cordeiro de Souza","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/"},"author":{"name":"Estev\u00e3o Leite Cordeiro de Souza","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf"},"headline":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio","datePublished":"2024-05-10T22:49:31+00:00","dateModified":"2024-05-13T16:40:38+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/"},"wordCount":718,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png","keywords":["Engenharia Civil","Engenharia de Produ\u00e7\u00e3o","Engenharia de Software","Engenharia El\u00e9trica","engenharias","EVENTOS","Eventos de Engenhria","Semana de Engenharia","Semana de Engenharia do UNIFSA","V Semana de Engenharia","V Semana de Engenharia do UNIFSA"],"articleSection":["Engenharia Civil","Engenharia de Produ\u00e7\u00e3o","Engenharia de Software","Engenharia El\u00e9trica","Eventos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/","url":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/","name":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png","datePublished":"2024-05-10T22:49:31+00:00","dateModified":"2024-05-13T16:40:38+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/05\/SITE-V-Semana-de-Engenharia-1920-x-805-px-2.png","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/v-semana-de-engenharia-do-unifsa-acontece-de-16-a-18-de-maio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"V Semana da Engenharia do UNIFSA acontece de 16 a 18 de maio"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/459d6944d25bd72102b031eb886c7cbf","name":"Estev\u00e3o Leite Cordeiro de Souza","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b381626173a0b440e86662336f5d92704de1b8100a4cb5a34d6466804eb5c336?s=96&d=mm&r=g","caption":"Estev\u00e3o Leite Cordeiro de Souza"},"url":"https:\/\/unifsa.com.br\/site\/author\/estevaocordeiro\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/31169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=31169"}],"version-history":[{"count":8,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/31169\/revisions"}],"predecessor-version":[{"id":31236,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/31169\/revisions\/31236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/31235"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=31169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=31169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=31169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}