{"id":30001,"date":"2024-04-01T19:12:25","date_gmt":"2024-04-01T22:12:25","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=30001"},"modified":"2024-04-05T19:51:55","modified_gmt":"2024-04-05T22:51:55","slug":"selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/","title":{"rendered":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA"},"content":{"rendered":"\n<p>O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Medicina Veterin\u00e1ria,\u00a0<strong>seleciona alunos monitores para o III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA.<\/strong>\u00a0O prazo vai de\u00a0<strong>1 a 3 de mar\u00e7o<\/strong>, com o custo de 1 (um) pacote de leite em p\u00f3 (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-red-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScKnMiJwtdV7lWSp-Ln8Y4DTAc4YFF_ZxFUSHqUUuJK8LsbFQ\/viewform?usp=send_form\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Inscreva-se para a Monitoria<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Edital-017-III-Jornada-Academica-de-Medicina-Veterinaria.pdf\" style=\"background-color:#0a78b8\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Edital de sele\u00e7\u00e3o completo <\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria acontecer\u00e1 de 9 a 11 de maio. Durante o evento, ser\u00e3o oferecidas palestras e minicursos voltados para a discuss\u00e3o dos mais recentes avan\u00e7os, desafios e oportunidades na \u00e1rea.<\/p>\n\n\n\n<p>Os candidatos pr\u00e9-selecionados ser\u00e3o convocados para uma entrevista, marcada para o dia 4 de abril, \u00e0s 11h, na Sala 206 do pr\u00e9dio Sede. O objetivo \u00e9 avaliar as habilidades atitudinais necess\u00e1rias para participa\u00e7\u00e3o na proposta de extens\u00e3o.<\/p>\n\n\n\n<p>Os extensionistas que n\u00e3o comparecerem na primeira semana de organiza\u00e7\u00e3o do evento ser\u00e3o automaticamente substitu\u00eddos pelos demais alunos classificados, seguindo a ordem de classifica\u00e7\u00e3o estabelecida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-badc84741e47adf37119205e88090627\">Crit\u00e9rios para participar da sele\u00e7\u00e3o:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dedicar-se, no per\u00edodo da vig\u00eancia do evento \u00e0s atividades propostas pela coordenadora sem preju\u00edzos das suas atividades discentes regulares;<\/li>\n\n\n\n<li class=\"texto-justificado\">Estar apto a iniciar as atividades relativas ao evento em 11\/04\/2024;<\/li>\n\n\n\n<li class=\"texto-justificado\">Ter entregue 1 (um) pacote de leite em p\u00f3 no NUAPE ap\u00f3s inscri\u00e7\u00e3o realizada.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-a260f33b031ab720d0e09cbdec92a958\">Saiba mais sobre a III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA:<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-centro-universit-rio-santo-agostinho-unifsa wp-block-embed-centro-universit-rio-santo-agostinho-unifsa\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"0eZhbAPC04\"><a href=\"https:\/\/unifsa.com.br\/site\/inscricoes-abertas-para-a-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\">III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA acontece em maio<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA acontece em maio&#8221; &#8212; Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" src=\"https:\/\/unifsa.com.br\/site\/inscricoes-abertas-para-a-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/embed\/#?secret=0N8RU9zUew#?secret=0eZhbAPC04\" data-secret=\"0eZhbAPC04\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Medicina Veterin\u00e1ria,\u00a0seleciona alunos monitores para o III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA.\u00a0O prazo vai de\u00a01 a 3 de mar\u00e7o, com o custo de 1 (um) pacote de leite em p\u00f3 (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). A III Jornada Acad\u00eamica de Medicina<\/p>\n","protected":false},"author":9,"featured_media":29998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1674,474],"tags":[331,1677,655,1675,1676,524],"class_list":["post-30001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-eventos","category-medicina-veterinaria","tag-evento","tag-iii-jornada-academica-de-medicina-veterinaria","tag-jornada-academica","tag-jornada-academica-2","tag-jornada-academica-de-medicina-veterinaria","tag-medicina-veterinaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Medicina Veterin\u00e1ria,\u00a0seleciona alunos monitores para o III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA.\u00a0O prazo vai de\u00a01 a 3 de mar\u00e7o, com o custo de 1 (um) pacote de leite em p\u00f3 (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). A III Jornada Acad\u00eamica de Medicina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T22:12:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T22:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La\u00eds Maria Matos Barradas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La\u00eds Maria Matos Barradas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\"},\"author\":{\"name\":\"La\u00eds Maria Matos Barradas\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8\"},\"headline\":\"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA\",\"datePublished\":\"2024-04-01T22:12:25+00:00\",\"dateModified\":\"2024-04-05T22:51:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png\",\"keywords\":[\"evento\",\"III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria\",\"Jornada Acad\u00eamica\",\"Jornada Academica\",\"Jornada Academica de Medicina Veterin\u00e1ria\",\"medicina veterin\u00e1ria\"],\"articleSection\":[\"Acontece na UNIFSA\",\"Eventos\",\"Medicina Veterin\u00e1ria\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\",\"name\":\"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png\",\"datePublished\":\"2024-04-01T22:12:25+00:00\",\"dateModified\":\"2024-04-05T22:51:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8\",\"name\":\"La\u00eds Maria Matos Barradas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g\",\"caption\":\"La\u00eds Maria Matos Barradas\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/laismbarradas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/","og_locale":"pt_BR","og_type":"article","og_title":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"O Centro Universit\u00e1rio Santo Agostinho, por meio do curso de Medicina Veterin\u00e1ria,\u00a0seleciona alunos monitores para o III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA.\u00a0O prazo vai de\u00a01 a 3 de mar\u00e7o, com o custo de 1 (um) pacote de leite em p\u00f3 (entregar no NUAPE ap\u00f3s a inscri\u00e7\u00e3o realizada). A III Jornada Acad\u00eamica de Medicina","og_url":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2024-04-01T22:12:25+00:00","article_modified_time":"2024-04-05T22:51:55+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png","type":"image\/png"}],"author":"La\u00eds Maria Matos Barradas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"La\u00eds Maria Matos Barradas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/"},"author":{"name":"La\u00eds Maria Matos Barradas","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8"},"headline":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA","datePublished":"2024-04-01T22:12:25+00:00","dateModified":"2024-04-05T22:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/"},"wordCount":261,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png","keywords":["evento","III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria","Jornada Acad\u00eamica","Jornada Academica","Jornada Academica de Medicina Veterin\u00e1ria","medicina veterin\u00e1ria"],"articleSection":["Acontece na UNIFSA","Eventos","Medicina Veterin\u00e1ria"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/","url":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/","name":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png","datePublished":"2024-04-01T22:12:25+00:00","dateModified":"2024-04-05T22:51:55+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2024\/04\/Formato-Sympla-1920-x-805-px.png","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/selecao-de-monitores-iii-jornada-academica-de-medicina-veterinaria-do-unifsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sele\u00e7\u00e3o de Monitores | III Jornada Acad\u00eamica de Medicina Veterin\u00e1ria do UNIFSA"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/415c79d344f0e698644c1d29997b4ea8","name":"La\u00eds Maria Matos Barradas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da15e6cd8e1aa267693a3720f1118763e970b03de2d998ee874f68b1f91042b8?s=96&d=mm&r=g","caption":"La\u00eds Maria Matos Barradas"},"url":"https:\/\/unifsa.com.br\/site\/author\/laismbarradas\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/30001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=30001"}],"version-history":[{"count":3,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/30001\/revisions"}],"predecessor-version":[{"id":30101,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/30001\/revisions\/30101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/29998"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=30001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=30001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=30001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}