{"id":18037,"date":"2022-12-03T10:49:11","date_gmt":"2022-12-03T13:49:11","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=18037"},"modified":"2022-12-03T10:49:13","modified_gmt":"2022-12-03T13:49:13","slug":"arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/","title":{"rendered":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete"},"content":{"rendered":"\n<p class=\"has-drop-cap texto-justificado\">As gradua\u00e7\u00f5es de <a href=\"https:\/\/unifsa.com.br\/site\/curso\/arquitetura-e-urbanismo\/\">Arquitetura e Urbanismo<\/a> e de <a href=\"https:\/\/unifsa.com.br\/site\/curso\/engenharia-civil\/\">Engenharia Civil<\/a> realizar\u00e3o, juntas, uma <strong>Competi\u00e7\u00e3o de Pontes de Espaguete<\/strong> no dia 06 de dezembro, \u00e0s 17h30, no Hall de Entrada do Anexo II do UNIFSA. A atividade faz parte da disciplina de Estruturas, ministrada pelo Prof. Esp. Leonardo Cunha do Nascimento.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote texto-justificado is-layout-flow wp-block-quote-is-layout-flow\"><p>A competi\u00e7\u00e3o de pontes de macarr\u00e3o \u00e9 uma atividade acad\u00eamica que visa a aplica\u00e7\u00e3o de conhecimentos de estabilidade das estruturas e resist\u00eancia dos materiais  atrav\u00e9s de um ensaio  de carga em treli\u00e7as de espaguete que simulam a capacidade resistente a esfor\u00e7os de tra\u00e7\u00e3o e compress\u00e3o de barras<\/p><cite> Prof. Esp. Leonardo Cunha do Nascimento, docente de Engenharia Civil UNIFSA<\/cite><\/blockquote>\n\n\n\n<p class=\"texto-justificado\">O docente complementa que o objetivo dessa competi\u00e7\u00e3o \u00e9 conduzir os participantes ao ensaio representativo das estruturas que permitam dimensionar, calcular e simular o comportamento da estrutura resistente, desenvolvendo, neles, habilidades de an\u00e1lise de estruturas,  gerenciamento de projeto e prospec\u00e7\u00e3o de riscos em etapas de planejamento de obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As gradua\u00e7\u00f5es de Arquitetura e Urbanismo e de Engenharia Civil realizar\u00e3o, juntas, uma Competi\u00e7\u00e3o de Pontes de Espaguete no dia 06 de dezembro, \u00e0s 17h30, no Hall de Entrada do Anexo II do UNIFSA.<\/p>\n","protected":false},"author":11,"featured_media":18184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,51,56],"tags":[746,125,1035,1036],"class_list":["post-18037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-arquitetura-urbanismo","category-engenharia-civil","tag-arquitetura-e-urbanismo","tag-engenharia-civil","tag-ponte-de-espaguete","tag-ponte-de-macarrao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"As gradua\u00e7\u00f5es de Arquitetura e Urbanismo e de Engenharia Civil realizar\u00e3o, juntas, uma Competi\u00e7\u00e3o de Pontes de Espaguete no dia 06 de dezembro, \u00e0s 17h30, no Hall de Entrada do Anexo II do UNIFSA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-03T13:49:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-03T13:49:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete\",\"datePublished\":\"2022-12-03T13:49:11+00:00\",\"dateModified\":\"2022-12-03T13:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg\",\"keywords\":[\"Arquitetura e Urbanismo\",\"Engenharia Civil\",\"Ponte de Espaguete\",\"Ponte de Macarr\u00e3o\"],\"articleSection\":[\"Acontece na UNIFSA\",\"Arquitetura e Urbanismo\",\"Engenharia Civil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\",\"name\":\"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg\",\"datePublished\":\"2022-12-03T13:49:11+00:00\",\"dateModified\":\"2022-12-03T13:49:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg\",\"width\":1920,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"As gradua\u00e7\u00f5es de Arquitetura e Urbanismo e de Engenharia Civil realizar\u00e3o, juntas, uma Competi\u00e7\u00e3o de Pontes de Espaguete no dia 06 de dezembro, \u00e0s 17h30, no Hall de Entrada do Anexo II do UNIFSA.","og_url":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2022-12-03T13:49:11+00:00","article_modified_time":"2022-12-03T13:49:13+00:00","og_image":[{"width":1920,"height":805,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg","type":"image\/jpeg"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete","datePublished":"2022-12-03T13:49:11+00:00","dateModified":"2022-12-03T13:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/"},"wordCount":180,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg","keywords":["Arquitetura e Urbanismo","Engenharia Civil","Ponte de Espaguete","Ponte de Macarr\u00e3o"],"articleSection":["Acontece na UNIFSA","Arquitetura e Urbanismo","Engenharia Civil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/","url":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/","name":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg","datePublished":"2022-12-03T13:49:11+00:00","dateModified":"2022-12-03T13:49:13+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/12\/site-macarr\u00e3o.jpg","width":1920,"height":805},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/arquitetura-e-engenharia-civil-realizam-competicao-de-pontes-de-espaguete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Arquitetura e Engenharia Civil realizam competi\u00e7\u00e3o de pontes de espaguete"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/18037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=18037"}],"version-history":[{"count":5,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/18037\/revisions"}],"predecessor-version":[{"id":18170,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/18037\/revisions\/18170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/18184"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=18037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=18037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=18037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}