{"id":12065,"date":"2022-03-03T14:25:08","date_gmt":"2022-03-03T17:25:08","guid":{"rendered":"https:\/\/unifsa.com.br\/site\/?p=12065"},"modified":"2022-03-03T14:25:11","modified_gmt":"2022-03-03T17:25:11","slug":"docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica","status":"publish","type":"post","link":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/","title":{"rendered":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica"},"content":{"rendered":"\n<p>A Professora <strong>Dra. M\u00e1rcia Cristiane Ara\u00fajo<\/strong>, do curso de Bacharelado em Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho, foi aprovada na sua defesa de tese de Doutorado em &#8220;Aspectos Biol\u00f3gicos Relacionados \u00e0 Atividade F\u00edsica e Sa\u00fade&#8221;, na Universidade Cat\u00f3lica de Bras\u00edlia\/UCB. Sua pesquisa \u00e9 o primeiro estudo no mundo a relacionar atividade f\u00edsica e diminui\u00e7\u00e3o da idade biol\u00f3gica.<\/p>\n\n\n\n<p>Segundo a docente, que faz parte da equipe UNIFSA h\u00e1 12 anos, o objetivo da pesquisa,  intitulada <strong>Associa\u00e7\u00e3o Entre Raz\u00e3o Adiponectina\/Leptina, Sirtu\u00edna 1, \u00cdndices De Adiposidade e o Comprimento Dos Tel\u00f4merose em Atletas Master<\/strong>, era investigar os par\u00e2metros de disfun\u00e7\u00e3o do tecido adiposo associado ao envelhecimento biol\u00f3gico, ou seja, o desejo era analisar se o treinamento f\u00edsico causa efeito positivo na idade biol\u00f3gica. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>N\u00f3s descobrimos que sim! O treinamento f\u00edsico faz com que voc\u00ea diminua o percentual de gordura e todos os \u00edndices de adiposidade e faz com que voc\u00ea aumente o tamanho dos tel\u00f4meros e a quantidade de Sirtu\u00edna 1, que s\u00e3o par\u00e2metros de idade biol\u00f3gica e faz com que voc\u00ea melhore os marcadores de disfun\u00e7\u00e3o do tecido adiposo, melhorando a sua sa\u00fade metab\u00f3lica.<\/p><cite> Profa. Dra. M\u00e1rcia Cristiane Ara\u00fajo, docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA<\/cite><\/blockquote>\n\n\n\n<p>Para desenvolver o trabalho, M\u00e1rcia comparou atletas Master (indiv\u00edduos de meia-idade, acima de quarenta anos, que se exercitam regularmente), com pessoas de mesma faixa et\u00e1ria, por\u00e9m sedent\u00e1rias, e tamb\u00e9m com indiv\u00edduos mais jovens (acima de 20 anos). A descoberta foi de que esses atletas Masters possuem a mesma idade biol\u00f3gica dos jovens com idade acima de 20 anos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Esse \u00e9 o primeiro estudo do mundo sobre o assunto. A gente vai publicar os artigos agora nas revistas internacionais, e vai ser bem interessante porque vai trazer uma s\u00e9ria de insights para a \u00e1rea da Educa\u00e7\u00e3o F\u00edsica, da biologia molecular, pois j\u00e1 t\u00ednhamos ideia de que o exerc\u00edcio \u00e9 capaz de melhorar a sa\u00fade biol\u00f3gica, mas n\u00e3o sab\u00edamos que esses exerc\u00edcios poderiam diminuir a idade biol\u00f3gica.<\/p><cite>  Profa. Dra. M\u00e1rcia Cristiane Ara\u00fajo, docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA <\/cite><\/blockquote>\n\n\n\n<p class=\"texto-justificado\">O UNIFSA parabeniza a professora M\u00e1rcia Cristiane pela aprova\u00e7\u00e3o e deseja sucesso em sua carreira!<\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background has-vivid-red-background-color\" href=\"https:\/\/unifsa.com.br\/site\/curso\/educacao-fisica-bacharelado\/\">Saiba mais sobre o curso de Educa\u00e7\u00e3o F\u00edsica UNIFSA!<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Professora Dra. M\u00e1rcia Cristiane Ara\u00fajo, do curso de Bacharelado em Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho, foi aprovada na sua defesa de tese de Doutorado em &#8220;Aspectos Biol\u00f3gicos Relacionados \u00e0 Atividade F\u00edsica e Sa\u00fade&#8221;, na Universidade Cat\u00f3lica de Bras\u00edlia\/UCB. Sua pesquisa \u00e9 o primeiro estudo no mundo a relacionar atividade f\u00edsica e diminui\u00e7\u00e3o da idade biol\u00f3gica.<\/p>\n","protected":false},"author":11,"featured_media":12081,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[175,118,186,695],"class_list":["post-12065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece-na-unifsa","category-educacao-fisica","tag-doutorado","tag-educacao-fisica","tag-saude","tag-tese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"og:description\" content=\"A Professora Dra. M\u00e1rcia Cristiane Ara\u00fajo, do curso de Bacharelado em Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho, foi aprovada na sua defesa de tese de Doutorado em &quot;Aspectos Biol\u00f3gicos Relacionados \u00e0 Atividade F\u00edsica e Sa\u00fade&quot;, na Universidade Cat\u00f3lica de Bras\u00edlia\/UCB. Sua pesquisa \u00e9 o primeiro estudo no mundo a relacionar atividade f\u00edsica e diminui\u00e7\u00e3o da idade biol\u00f3gica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unifsa\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-03T17:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T17:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oceannyra Kelly da Cruz Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\"},\"author\":{\"name\":\"Oceannyra Kelly da Cruz Silva\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\"},\"headline\":\"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica\",\"datePublished\":\"2022-03-03T17:25:08+00:00\",\"dateModified\":\"2022-03-03T17:25:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png\",\"keywords\":[\"Doutorado\",\"Educa\u00e7\u00e3o F\u00edsica\",\"Sa\u00fade\",\"tese\"],\"articleSection\":[\"Acontece na UNIFSA\",\"Educa\u00e7\u00e3o F\u00edsica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\",\"name\":\"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"isPartOf\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png\",\"datePublished\":\"2022-03-03T17:25:08+00:00\",\"dateModified\":\"2022-03-03T17:25:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/unifsa.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#website\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"description\":\"Conhecimento para toda a vida\",\"publisher\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unifsa.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#organization\",\"name\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\",\"url\":\"https:\/\/unifsa.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"contentUrl\":\"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png\",\"width\":103,\"height\":100,\"caption\":\"Centro Universit\u00e1rio Santo Agostinho - UNIFSA\"},\"image\":{\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unifsa\/\",\"https:\/\/www.instagram.com\/unifsa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2\",\"name\":\"Oceannyra Kelly da Cruz Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g\",\"caption\":\"Oceannyra Kelly da Cruz Silva\"},\"url\":\"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/","og_locale":"pt_BR","og_type":"article","og_title":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","og_description":"A Professora Dra. M\u00e1rcia Cristiane Ara\u00fajo, do curso de Bacharelado em Educa\u00e7\u00e3o F\u00edsica do Centro Universit\u00e1rio Santo Agostinho, foi aprovada na sua defesa de tese de Doutorado em \"Aspectos Biol\u00f3gicos Relacionados \u00e0 Atividade F\u00edsica e Sa\u00fade\", na Universidade Cat\u00f3lica de Bras\u00edlia\/UCB. Sua pesquisa \u00e9 o primeiro estudo no mundo a relacionar atividade f\u00edsica e diminui\u00e7\u00e3o da idade biol\u00f3gica.","og_url":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/","og_site_name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","article_publisher":"https:\/\/www.facebook.com\/unifsa\/","article_published_time":"2022-03-03T17:25:08+00:00","article_modified_time":"2022-03-03T17:25:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png","type":"image\/png"}],"author":"Oceannyra Kelly da Cruz Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Oceannyra Kelly da Cruz Silva","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#article","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/"},"author":{"name":"Oceannyra Kelly da Cruz Silva","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2"},"headline":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica","datePublished":"2022-03-03T17:25:08+00:00","dateModified":"2022-03-03T17:25:11+00:00","mainEntityOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/"},"wordCount":430,"publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png","keywords":["Doutorado","Educa\u00e7\u00e3o F\u00edsica","Sa\u00fade","tese"],"articleSection":["Acontece na UNIFSA","Educa\u00e7\u00e3o F\u00edsica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/","url":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/","name":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica - Centro Universit\u00e1rio Santo Agostinho - UNIFSA","isPartOf":{"@id":"https:\/\/unifsa.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage"},"thumbnailUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png","datePublished":"2022-03-03T17:25:08+00:00","dateModified":"2022-03-03T17:25:11+00:00","breadcrumb":{"@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#primaryimage","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2022\/03\/prof-ed-fisica-site.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/unifsa.com.br\/site\/docente-de-educacao-fisica-unifsa-defende-tese-sobre-a-importancia-dos-exercicios-fisicos-na-idade-biologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/unifsa.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Docente de Educa\u00e7\u00e3o F\u00edsica UNIFSA defende tese sobre a import\u00e2ncia dos exerc\u00edcios f\u00edsicos na idade biol\u00f3gica"}]},{"@type":"WebSite","@id":"https:\/\/unifsa.com.br\/site\/#website","url":"https:\/\/unifsa.com.br\/site\/","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","description":"Conhecimento para toda a vida","publisher":{"@id":"https:\/\/unifsa.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unifsa.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/unifsa.com.br\/site\/#organization","name":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA","url":"https:\/\/unifsa.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","contentUrl":"https:\/\/unifsa.com.br\/site\/wp-content\/uploads\/2023\/03\/MARCA-UNIFSA-CIC23-q2apjs1mt975cf1wl25b044coj90fwoiee1kya6800.png","width":103,"height":100,"caption":"Centro Universit\u00e1rio Santo Agostinho - UNIFSA"},"image":{"@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unifsa\/","https:\/\/www.instagram.com\/unifsa\/"]},{"@type":"Person","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/a4cec94bbc6ddf98f579162824de9bf2","name":"Oceannyra Kelly da Cruz Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/unifsa.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05c87cd6fa2c3c73262055bd9341438a47e77a37053b409b3cf4f8df60ea8eb8?s=96&d=mm&r=g","caption":"Oceannyra Kelly da Cruz Silva"},"url":"https:\/\/unifsa.com.br\/site\/author\/oceannyrakelly\/"}]}},"_links":{"self":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/12065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/comments?post=12065"}],"version-history":[{"count":5,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/12065\/revisions"}],"predecessor-version":[{"id":12079,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/posts\/12065\/revisions\/12079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media\/12081"}],"wp:attachment":[{"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/media?parent=12065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/categories?post=12065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unifsa.com.br\/site\/wp-json\/wp\/v2\/tags?post=12065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}